{"id":8202,"date":"2018-10-28T08:47:38","date_gmt":"2018-10-28T08:47:38","guid":{"rendered":"https:\/\/www.totemmt.com\/?page_id=8202"},"modified":"2025-08-19T10:44:10","modified_gmt":"2025-08-19T10:44:10","slug":"home","status":"publish","type":"page","link":"https:\/\/www.totemmt.com\/eu\/","title":{"rendered":"Totem\u00ae MT | Eskaladarako materiala | Denda"},"content":{"rendered":"<div class=\"bxslider-home\">\n<div>\n<img decoding=\"async\" class=\"home-slider-desktop\" src=\"https:\/\/www.totemmt.com\/wp-content\/uploads\/2020\/04\/TotemCam080_desktop.jpg\"><br \/>\n<a class=\"home-slider-mobile\" href=\"https:\/\/www.totemmt.com\/eu\/produktua\/totem-camtotem-cam\/\"><img decoding=\"async\" src=\"https:\/\/www.totemmt.com\/wp-content\/uploads\/2020\/04\/TotemCam080_mobile.jpg\"> <\/a><\/p>\n<div class=\"home-slider home-slider1\">\n<p class=\"home-slider-text1\">TOTEM CAM<br \/>\nestandar berria<\/p>\n<p class=\"home-slider-button\"><a class=\"button alt\" href=\"https:\/\/www.totemmt.com\/eu\/produktua\/totem-cam\/\">Informazio gehiago <i class=\"fa fa-shopping-cart\"><\/i><\/a><\/p>\n<p class=\"home-slider-text1 worldwide-shipping-desktop rest_world\"><em>48h bidalketa doan!!<\/em><\/p>\n<p class=\"home-slider-text1 worldwide-shipping-desktop US\"><em>AEBetara 72h bidalketa doan!<\/em><\/p>\n<\/div>\n<div class=\"worldwide-shipping-mobile rest_world\"><em>48h bidalketa doan!!<\/em><\/div>\n<div class=\"worldwide-shipping-mobile US\"><em>AEBetara 72h bidalketa doan!<\/em><\/div>\n<\/div>\n<div><img decoding=\"async\" class=\"home-slider-desktop\" src=\"https:\/\/www.totemmt.com\/wp-content\/uploads\/2025\/06\/TMLLAVEROS_paredblanca.webp\"><br \/>\n    <a class=\"home-slider-mobile\" href=\"https:\/\/www.totemmt.com\/2020\/11\/salathe-wall\/\"><img decoding=\"async\" src=\"https:\/\/www.totemmt.com\/wp-content\/uploads\/llaveros\/TMLLAVEROS_paredblanca.webp\"><\/a><\/p>\n<div class=\"home-slider home-slider1\">\n<p class=\"home-slider-text1\">Lortu giltzatako bat gutxienez hiru TOTEM CAMeko erosketarekin<\/p>\n<p class=\"home-slider-button\"><a class=\"button alt\" href=\"https:\/\/www.totemmt.com\/product\/totem-cam\">Erosi orain <i class=\"fa fa-shopping-cart\"><\/i><\/a><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<div><img decoding=\"async\" class=\"home-slider-desktop\" src=\"https:\/\/www.totemmt.com\/wp-content\/uploads\/2025\/05\/27A7698_Crown%20Royale_2nd.webp\"><br \/>\n    <a class=\"home-slider-mobile\" href=\"https:\/\/www.totemmt.com\/2020\/11\/salathe-wall\/\"><img decoding=\"async\" src=\"https:\/\/www.totemmt.com\/wp-content\/uploads\/2025\/05\/27A7698_Crown%20Royale_2nd.webp\"><\/a><\/p>\n<div class=\"home-slider home-slider2\">\n<p class=\"home-slider-text2\">Crown Royale, 9a trad. Jernej Kruderren bigarren igoera<\/p>\n<p class=\"home-slider-button\"><a class=\"button alt\" href=\"https:\/\/www.totemmt.com\/2025\/05\/crown-royale-9a-trad-second-ascent-by-jernej-kruder\/\">Gehiago irakurri<\/a><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>TOTEM CAM estandar berria Informazio gehiago 48h bidalketa doan!! AEBetara 72h bidalketa doan! 48h bidalketa doan!! AEBetara 72h bidalketa doan! Lortu giltzatako bat gutxienez hiru TOTEM CAMeko erosketarekin Erosi orain Crown Royale, 9a trad. Jernej Kruderren bigarren igoera Gehiago irakurri<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"wpupg_custom_link":[],"wpupg_custom_link_behaviour":[],"wpupg_custom_link_nofollow":[],"wpupg_custom_image":[],"wpupg_custom_image_id":[],"footnotes":""},"class_list":["post-8202","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Totem\u00ae MT | Eskaladarako materiala | Denda<\/title>\n<meta name=\"description\" content=\"Totem MT, eskaladarako material ekoizlea da. Totem Cam produtua izan da gure lehenengoa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.totemmt.com\/eu\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Totem\u00ae MT | Eskaladarako materiala | Denda\" \/>\n<meta property=\"og:description\" content=\"Totem MT, eskaladarako material ekoizlea da. Totem Cam produtua izan da gure lehenengoa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.totemmt.com\/eu\/\" \/>\n<meta property=\"og:site_name\" content=\"Totem MT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/totemcams\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T10:44:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.totemmt.com\/wp-content\/uploads\/2020\/04\/TotemCam080_desktop.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@totemmt\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/eu\\\/\",\"url\":\"https:\\\/\\\/www.totemmt.com\\\/eu\\\/\",\"name\":\"Totem\u00ae MT | Eskaladarako materiala | Denda\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/eu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/eu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.totemmt.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/TotemCam080_desktop.jpg\",\"datePublished\":\"2018-10-28T08:47:38+00:00\",\"dateModified\":\"2025-08-19T10:44:10+00:00\",\"description\":\"Totem MT, eskaladarako material ekoizlea da. Totem Cam produtua izan da gure lehenengoa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/eu\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.totemmt.com\\\/eu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/eu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.totemmt.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/TotemCam080_desktop.jpg\",\"contentUrl\":\"https:\\\/\\\/www.totemmt.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/TotemCam080_desktop.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/eu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.totemmt.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Totem\u00ae MT | Eskaladarako materiala | Denda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/#website\",\"url\":\"https:\\\/\\\/www.totemmt.com\\\/\",\"name\":\"Totem MT\",\"description\":\"Totem MT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.totemmt.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/#organization\",\"name\":\"Totem MT\",\"url\":\"https:\\\/\\\/www.totemmt.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.totemmt.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/TotemLogo.png\",\"contentUrl\":\"https:\\\/\\\/www.totemmt.com\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/TotemLogo.png\",\"width\":364,\"height\":138,\"caption\":\"Totem MT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.totemmt.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/totemcams\",\"https:\\\/\\\/x.com\\\/totemmt\",\"https:\\\/\\\/instagram.com\\\/totemmt\\\/\",\"https:\\\/\\\/www.youtube.com\\\/totemmt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Totem\u00ae MT | Eskaladarako materiala | Denda","description":"Totem MT, eskaladarako material ekoizlea da. Totem Cam produtua izan da gure lehenengoa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.totemmt.com\/eu\/","og_locale":"eu_ES","og_type":"article","og_title":"Totem\u00ae MT | Eskaladarako materiala | Denda","og_description":"Totem MT, eskaladarako material ekoizlea da. Totem Cam produtua izan da gure lehenengoa.","og_url":"https:\/\/www.totemmt.com\/eu\/","og_site_name":"Totem MT","article_publisher":"https:\/\/www.facebook.com\/totemcams","article_modified_time":"2025-08-19T10:44:10+00:00","og_image":[{"url":"https:\/\/www.totemmt.com\/wp-content\/uploads\/2020\/04\/TotemCam080_desktop.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@totemmt","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.totemmt.com\/eu\/","url":"https:\/\/www.totemmt.com\/eu\/","name":"Totem\u00ae MT | Eskaladarako materiala | Denda","isPartOf":{"@id":"https:\/\/www.totemmt.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.totemmt.com\/eu\/#primaryimage"},"image":{"@id":"https:\/\/www.totemmt.com\/eu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.totemmt.com\/wp-content\/uploads\/2020\/04\/TotemCam080_desktop.jpg","datePublished":"2018-10-28T08:47:38+00:00","dateModified":"2025-08-19T10:44:10+00:00","description":"Totem MT, eskaladarako material ekoizlea da. Totem Cam produtua izan da gure lehenengoa.","breadcrumb":{"@id":"https:\/\/www.totemmt.com\/eu\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.totemmt.com\/eu\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.totemmt.com\/eu\/#primaryimage","url":"https:\/\/www.totemmt.com\/wp-content\/uploads\/2020\/04\/TotemCam080_desktop.jpg","contentUrl":"https:\/\/www.totemmt.com\/wp-content\/uploads\/2020\/04\/TotemCam080_desktop.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.totemmt.com\/eu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.totemmt.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Totem\u00ae MT | Eskaladarako materiala | Denda"}]},{"@type":"WebSite","@id":"https:\/\/www.totemmt.com\/#website","url":"https:\/\/www.totemmt.com\/","name":"Totem MT","description":"Totem MT","publisher":{"@id":"https:\/\/www.totemmt.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.totemmt.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.totemmt.com\/#organization","name":"Totem MT","url":"https:\/\/www.totemmt.com\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.totemmt.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.totemmt.com\/wp-content\/uploads\/2018\/05\/TotemLogo.png","contentUrl":"https:\/\/www.totemmt.com\/wp-content\/uploads\/2018\/05\/TotemLogo.png","width":364,"height":138,"caption":"Totem MT"},"image":{"@id":"https:\/\/www.totemmt.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/totemcams","https:\/\/x.com\/totemmt","https:\/\/instagram.com\/totemmt\/","https:\/\/www.youtube.com\/totemmt"]}]}},"_links":{"self":[{"href":"https:\/\/www.totemmt.com\/eu\/wp-json\/wp\/v2\/pages\/8202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.totemmt.com\/eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.totemmt.com\/eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.totemmt.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.totemmt.com\/eu\/wp-json\/wp\/v2\/comments?post=8202"}],"version-history":[{"count":48,"href":"https:\/\/www.totemmt.com\/eu\/wp-json\/wp\/v2\/pages\/8202\/revisions"}],"predecessor-version":[{"id":21149,"href":"https:\/\/www.totemmt.com\/eu\/wp-json\/wp\/v2\/pages\/8202\/revisions\/21149"}],"wp:attachment":[{"href":"https:\/\/www.totemmt.com\/eu\/wp-json\/wp\/v2\/media?parent=8202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}